{"id":1141,"count":1,"description":"","link":"https:\/\/www.organizasyonekipmanlari.com.tr\/ro\/tag\/ozel-davet-dekorasyonu\/","name":"decorarea evenimentelor private","slug":"ozel-davet-dekorasyonu","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/ro\/wp-json\/wp\/v2\/tags\/1141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/ro\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/ro\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/ro\/wp-json\/wp\/v2\/posts?tags=1141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}