{"id":3525,"date":"2026-05-10T16:07:27","date_gmt":"2026-05-10T16:07:27","guid":{"rendered":"https:\/\/www.organizasyonekipmanlari.com.tr\/?post_type=product&#038;p=3525"},"modified":"2026-05-10T16:20:53","modified_gmt":"2026-05-10T16:20:53","slug":"dasma-sandalye","status":"publish","type":"product","link":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/dasma-sandalye\/","title":{"rendered":"Sedia Dasma"},"content":{"rendered":"<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-275\" data-path-to-node=\"7\"><span data-path-to-node=\"7,0\">La serie Dasma \u00e8 un modello prestigioso che si distingue per la sua robustezza e l'elegante design del retro, realizzato con tecnologia di stampaggio a iniezione monoblocco.<\/span><span data-path-to-node=\"7,2\"> Grazie alla sua struttura monoblocco, non si allenta nelle giunture ed \u00e8 ideale per sale per ricevimenti con elevato flusso di persone.<\/span><\/p>\n<h3 data-path-to-node=\"8\">Variazioni di colore Dasma<\/h3>\n<p data-path-to-node=\"9\"><b data-path-to-node=\"9\" data-index-in-node=\"0\">1. Sedia Dasma bianca: purezza senza tempo<\/b><\/p>\n<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-276\" data-path-to-node=\"10,0,0\"><span data-path-to-node=\"10,0,0,0\">Un prodotto indispensabile per chi organizza matrimoni, Beyaz Dasma non ingiallisce al sole grazie alla sua formula resistente ai raggi UV.<\/span><span data-path-to-node=\"10,0,0,2\"> Rappresenta la purezza, ideale per giardini di campagna e sale spaziose.<\/span><\/p>\n<p data-path-to-node=\"11\"><b data-path-to-node=\"11\" data-index-in-node=\"0\">2. Sedia Dasma nera: autorit\u00e0 moderna<\/b><\/p>\n<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-277\" data-path-to-node=\"12,0,0\"><span data-path-to-node=\"12,0,0,0\">Per chi desidera un'atmosfera sofisticata e di grande impatto, la lampada Dasma nera offre un contrasto perfetto con i dettagli metallici.<\/span><span data-path-to-node=\"12,0,0,2\"> La sua capacit\u00e0 di nascondere macchie e polvere ne facilita l'utilizzo.<\/span><\/p>\n<p data-path-to-node=\"13\"><b data-path-to-node=\"13\" data-index-in-node=\"0\">3. Sedia Silver Dasma: eleganza tecnologica<\/b><\/p>\n<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-278\" data-path-to-node=\"14,0,0\"><span data-path-to-node=\"14,0,0,0\">Il riflesso argentato metallico accentua i dettagli delle linee sul retro della Dasma, aggiungendo un'eleganza futuristica all'ambiente. Grazie alla vernice resistente alla ruggine e allo sbiadimento, rappresenta un investimento destinato a durare nel tempo.<\/span><\/p>\n<p data-path-to-node=\"15\"><b data-path-to-node=\"15\" data-index-in-node=\"0\">4. Sedia Dasma dorata: Splendore da palazzo<\/b><\/p>\n<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-279\" data-path-to-node=\"16,0,0\"><span data-path-to-node=\"16,0,0,0\">Gold Dasma, la stella splendente dei matrimoni a tema \"reale\", conserva la sua lucentezza dorata per anni grazie alla speciale verniciatura a forno.<\/span><span data-path-to-node=\"16,0,0,2\"> Abbinato a tovagliette eleganti, eleva l'armonia visiva al suo apice.<\/span><\/p>\n<p data-path-to-node=\"17\"><b data-path-to-node=\"17\" data-index-in-node=\"0\">5. Sedia Pearl Dasma: sofisticata eleganza in madreperla<\/b><\/p>\n<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-280\" data-path-to-node=\"18,0,0\"><span data-path-to-node=\"18,0,0,0\">Per chi desidera una texture perlata che eviti la piattezza del bianco, la vernice perlata Dasma offre un affascinante luccichio sotto una luce soffusa.<\/span><\/p>\n<h2 data-path-to-node=\"21\">Altri modelli popolari: Svadba, Mila e Venus<\/h2>\n<ul data-path-to-node=\"22\">\n<li>\n<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-286\" data-path-to-node=\"22,0,0\"><span data-path-to-node=\"22,0,0,0\"><b data-path-to-node=\"22,0,0,0\" data-index-in-node=\"0\">Serie di matrimoni:<\/b> Descritto come \"il dettaglio scintillante delle notti luccicanti\", il suo esclusivo design posteriore lo rende uno dei preferiti nelle location per matrimoni.<\/span><\/p>\n<\/li>\n<li>\n<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-287\" data-path-to-node=\"22,1,0\"><span data-path-to-node=\"22,1,0,0\"><b data-path-to-node=\"22,1,0,0\" data-index-in-node=\"0\">Mila Trasparente:<\/b> Con la sua struttura trasparente come il vetro ma resistente come l'acciaio, rappresenta l'apice dell'arredamento minimalista.<\/span><\/p>\n<\/li>\n<li>\n<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-288\" data-path-to-node=\"22,2,0\"><span data-path-to-node=\"22,2,0,0\"><b data-path-to-node=\"22,2,0,0\" data-index-in-node=\"0\">Venere Trasparente:<\/b> Caratterizzato da una silhouette moderna con il suo design posteriore arrotondato, questo modello \u00e8 esteticamente gradevole ed \u00e8 particolarmente apprezzato per eventi prestigiosi.<\/span><\/p>\n<\/li>\n<\/ul>\n<h2 data-path-to-node=\"30\"><\/h2>\n<h2 data-path-to-node=\"30\">Informazioni su manutenzione, pulizia e funzionamento<\/h2>\n<p data-path-to-node=\"31\">Per prolungare la durata dei prodotti polimerici, \u00e8 necessario seguire i seguenti protocolli:<\/p>\n<ul data-path-to-node=\"32\">\n<li>\n<p id=\"p-c_02c00fb98604aed9_ce7b8231-9f4a-4d22-8344-9f4a4d228344-289\" data-path-to-node=\"32,0,0\"><span data-path-to-node=\"32,0,0,0\"><b data-path-to-node=\"32,0,0,0\" data-index-in-node=\"0\">Protezione delle superfici:<\/b> Per evitare graffi, si consiglia di utilizzare un panno morbido in microfibra e acqua tiepida saponata.<\/span><\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"32,1,0\"><b data-path-to-node=\"32,1,0\" data-index-in-node=\"0\">Avvertenza sui prodotti chimici:<\/b> I detergenti contenenti ammoniaca, alcol o solventi aggressivi possono opacizzare la superficie.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"32,2,0\"><b data-path-to-node=\"32,2,0\" data-index-in-node=\"0\">Modelli dipinti:<\/b> Per le superfici verniciate come oro e argento, l'asciugatura dopo la pulizia \u00e8 fondamentale per mantenerne la lucentezza.<\/p>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><span data-path-to-node=\"7,0\">La serie Dasma \u00e8 un modello prestigioso che si distingue per la sua robustezza e l'elegante design del retro, realizzato con tecnologia di stampaggio a iniezione monoblocco.<\/span><span data-path-to-node=\"7,2\"> Grazie alla sua struttura monoblocco, non si allenta nelle giunture ed \u00e8 ideale per sale per ricevimenti con elevato flusso di persone.<\/span><\/p>","protected":false},"featured_media":3533,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[59,94],"product_tag":[220,397,351],"class_list":["post-3525","product","type-product","status-publish","has-post-thumbnail","product_cat-sandalye-masa","product_cat-sandalye-cesitleri","product_tag-dugun-sandalyesi","product_tag-kirilmaz-sandalye","product_tag-polikarbon-sandalye","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/wp-json\/wp\/v2\/product\/3525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/wp-json\/wp\/v2\/comments?post=3525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/wp-json\/wp\/v2\/media\/3533"}],"wp:attachment":[{"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/wp-json\/wp\/v2\/media?parent=3525"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/wp-json\/wp\/v2\/product_brand?post=3525"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/wp-json\/wp\/v2\/product_cat?post=3525"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.organizasyonekipmanlari.com.tr\/it\/wp-json\/wp\/v2\/product_tag?post=3525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}